{"id":2323,"date":"2020-10-08T20:56:00","date_gmt":"2020-10-08T20:56:00","guid":{"rendered":"https:\/\/loadzx.com\/loadvisitorguide\/?page_id=2323"},"modified":"2021-11-05T03:09:30","modified_gmt":"2021-11-05T03:09:30","slug":"pt-c30260","status":"publish","type":"page","link":"https:\/\/loadzx.com\/loadvisitorguide\/pt-c30260\/","title":{"rendered":"30260 &#8211; Amstrad CPC 464"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2323\" class=\"elementor elementor-2323\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-4bd9efd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"87028\" data-id=\"4bd9efd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c81ffa\" data-eae-slider=\"5840\" data-id=\"1c81ffa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0667f4b elementor-widget elementor-widget-heading\" data-id=\"0667f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Guia de Visita<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-72897bd elementor-section-items-top elementor-section-content-middle elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-eae-slider=\"28912\" data-id=\"72897bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-7199241\" data-eae-slider=\"4597\" data-id=\"7199241\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39cbef1 elementor-widget elementor-widget-heading\" data-id=\"39cbef1\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"headCurPage\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NNNNN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-65c3dcf\" data-eae-slider=\"82127\" data-id=\"65c3dcf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-7258c70\" data-eae-slider=\"17331\" data-id=\"7258c70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cbf277 elementor-widget elementor-widget-html\" data-id=\"5cbf277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<label for=\"textNumberPage\"><\/label>\r\n\r\n<input type=\"text\" id=\"textNumberPage\" name=\"textNumberPage\" required\r\n       minlength=\"1\" maxlength=\"5\" size=\"5\" style=\"font-size: 8px; max-width:200px;height: 24px;\">\r\n \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-68e3d23\" data-eae-slider=\"88915\" data-id=\"68e3d23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32581e7 elementor-button-success elementor-align-left elementor-widget elementor-widget-button\" data-id=\"32581e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/loadzx.com\/loadvisitorguide\/pt-c1\" id=\"numberPageGo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">GO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-a5924cf\" data-eae-slider=\"95809\" data-id=\"a5924cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0783365 elementor-button-success elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0783365\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/loadzx.com\/loadvisitorguide\/C1\" id=\"headJumpFirst\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">#1<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-9b956bc\" data-eae-slider=\"72268\" data-id=\"9b956bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-0a2cd7e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"39716\" data-id=\"0a2cd7e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f2d0124\" data-eae-slider=\"58435\" data-id=\"f2d0124\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ded4ff9 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"ded4ff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/loadzx.com\/loadvisitorguide\/tvcontents\/pt\/C1\" id=\"ptLink\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ffa3a77\" data-eae-slider=\"63557\" data-id=\"ffa3a77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a13164 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9a13164\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/loadzx.com\/loadvisitorguide\/tvcontents\/en\/C1\" id=\"enLink\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-31f0608\" data-eae-slider=\"8492\" data-id=\"31f0608\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87fdbea elementor-align-left elementor-widget elementor-widget-button\" data-id=\"87fdbea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/loadzx.com\/loadvisitorguide\/tvcontents\/es\/C1\" id=\"esLink\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ES<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-a480353 elementor-hidden-phone\" data-eae-slider=\"39647\" data-id=\"a480353\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-2a45b49\" data-eae-slider=\"76793\" data-id=\"2a45b49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d82bfb4 elementor-widget elementor-widget-image\" data-id=\"d82bfb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"133\" src=\"https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/03\/logo_LOAD_cor_invertido-smaller_borders-300x133.png\" class=\"attachment-medium size-medium wp-image-1179\" alt=\"\" srcset=\"https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/03\/logo_LOAD_cor_invertido-smaller_borders-300x133.png 300w, https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/03\/logo_LOAD_cor_invertido-smaller_borders-768x342.png 768w, https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/03\/logo_LOAD_cor_invertido-smaller_borders.png 904w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-9e8d5cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"38988\" data-id=\"9e8d5cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b8e6c10\" data-eae-slider=\"34557\" data-id=\"b8e6c10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf596d4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bf596d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/loadzx.com\/loadvisitorguide\/c1\" id=\"previousNavigation\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-left\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-95ae447\" data-eae-slider=\"26028\" data-id=\"95ae447\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-17b9aea\" data-eae-slider=\"19986\" data-id=\"17b9aea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-033f518 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"033f518\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/loadzx.com\/loadvisitorguide\/c4\" id=\"nextNavigation\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-acda2f3 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"43475\" data-id=\"acda2f3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd34f7d\" data-eae-slider=\"59470\" data-id=\"fd34f7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-5dbb992 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"58828\" data-id=\"5dbb992\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fd1e495\" data-eae-slider=\"2562\" data-id=\"fd1e495\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d7cb1d elementor-widget elementor-widget-heading\" data-id=\"0d7cb1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AMSTRAD CPC 464<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd5a39 elementor-widget elementor-widget-text-editor\" data-id=\"4fd5a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com mais de 2 milh\u00f5es de unidades vendidas na Europa, o <strong>Amstrad CPC 464<\/strong> foi, a par do Commodore 64 e do BBC Micro, um dos principais competidores do ZX Spectrum.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-040e576 elementor-widget elementor-widget-image\" data-id=\"040e576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"461\" height=\"307\" src=\"https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/09\/Imagem70.jpg\" class=\"attachment-large size-large wp-image-1798\" alt=\"\" srcset=\"https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/09\/Imagem70.jpg 461w, https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/09\/Imagem70-300x200.jpg 300w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a37c024 elementor-widget elementor-widget-text-editor\" data-id=\"a37c024\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCriado pelo do Eng. Ivor Spital, o <strong>CPC 464<\/strong> surge da vontade da Amstrad em investir no emergente mercado de Micro Computadores, para contrariar a estagna\u00e7\u00e3o da eletr\u00f3nica de consumo no inicio dos anos 80.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96ba812 elementor-widget elementor-widget-text-editor\" data-id=\"96ba812\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tO <strong>CPC 464<\/strong> era significativamente mais competente para jogos que as m\u00e1quinas da Sinclair, mas a sua menor fatia de mercado fez com que as suas potencialidades raramente fossem aproveitadas, tendo sido inundado por portos de qualidade duvidosa de outras plataformas.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfc1424 elementor-widget elementor-widget-image\" data-id=\"cfc1424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"275\" height=\"194\" src=\"https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/09\/Imagem71.jpg\" class=\"attachment-large size-large wp-image-1799\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-507777f elementor-widget elementor-widget-text-editor\" data-id=\"507777f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tA linha <strong>CPC<\/strong> da Amstrad foi tamb\u00e9m comercializada pela Schneider pelo que \u00e9 frequente encontrar estas vers\u00f5es na Alemanha e Su\u00ed\u00e7a.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea71937 elementor-widget elementor-widget-text-editor\" data-id=\"ea71937\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAquando do seu lan\u00e7amento em 1984 o <strong>CPC 464<\/strong> tinha um teclado profissional e um leitor de cassetes acoplado, e custava apenas \u00a3249 (com monitor inclu\u00eddo), sendo um competidor de peso para o comparativamente \u201cb\u00e1sico\u201d ZX Spectrum.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6772cb7 elementor-widget elementor-widget-image\" data-id=\"6772cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"269\" height=\"190\" src=\"https:\/\/loadzx.com\/loadvisitorguide\/wp-content\/uploads\/2020\/09\/Imagem72.jpg\" class=\"attachment-large size-large wp-image-1800\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1344d68 elementor-widget elementor-widget-text-editor\" data-id=\"1344d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"text-decoration: underline;\">Especifica\u00e7\u00f5es T\u00e9cnicas:<\/span>\n<br>\nAno de Lan\u00e7amento: 1984\n<br>\nProcessador: Zilog Z80 a 4 Mhz\n<br>\nMem\u00f3ria: 64K\n<br>\nResolu\u00e7\u00e3o: M\u00e1xima 640&#215;200 (2 cores) \/ Comum 160&#215;200 (16 cores)\n<br>\nSom: AY-3-8912 (3 vozes)\n<br>\nMedia: Cassetes\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db3287c elementor-widget elementor-widget-spacer\" data-id=\"db3287c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cae580 elementor-widget elementor-widget-html\" data-id=\"8cae580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"top-link hide\" href=\"\" id=\"js-top\">\r\n  <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 12 6\"><path d=\"M12 6H0l6-6z\"\/><\/svg>\r\n  <span class=\"screen-reader-text\">Back to top<\/span>\r\n<\/a>\r\n\r\n<style>\r\n\r\n\r\n.intro-copy {\r\n  padding: 1em;\r\n  margin: 50vh auto;\r\n  max-width: 15em;\r\n  font-family: Helvetica;\r\n  font-weight: lighter;\r\n  font-size: 2em;\r\n  line-height: 1.2;\r\n  text-align: center;\r\n}\r\n\r\n.top-link {\r\n    z-index: 99999;\r\n  transition: all .25s ease-in-out;\r\n  position: fixed;\r\n  bottom: 0;\r\n  right: 0;\r\n  display: inline-flex;\r\n  cursor: pointer;\r\n  align-items: center;\r\n  justify-content: center;\r\n  margin: 0 3em 3em 0;\r\n  border-radius: 50%;\r\n  padding: .25em;\r\n  width: 50px;\r\n  height: 50px;\r\n  background-color: #F8F8F8;\r\n}\r\n.top-link.show {\r\n  visibility: visible;\r\n  opacity: 1;\r\n}\r\n.top-link.hide {\r\n  visibility: hidden;\r\n  opacity: 0;\r\n}\r\n.top-link svg {\r\n  fill: #000;\r\n  width: 24px;\r\n  height: 12px;\r\n}\r\n.top-link:hover {\r\n  background-color: #E8E8E8;\r\n}\r\n.top-link:hover svg {\r\n  fill: #000000;\r\n}\r\n\r\n.screen-reader-text {\r\n  position: absolute;\r\n  clip-path: inset(50%);\r\n  margin: -1px;\r\n  border: 0;\r\n  padding: 0;\r\n  width: 1px;\r\n  height: 1px;\r\n  overflow: hidden;\r\n  word-wrap: normal !important;\r\n  clip: rect(1px, 1px, 1px, 1px);\r\n}\r\n.screen-reader-text:focus {\r\n  display: block;\r\n  top: 5px;\r\n  left: 5px;\r\n  z-index: 100000;\r\n  clip-path: none;\r\n  background-color: #eee;\r\n  padding: 15px 23px 14px;\r\n  width: auto;\r\n  height: auto;\r\n  text-decoration: none;\r\n  line-height: normal;\r\n  color: #444;\r\n  font-size: 1em;\r\n  clip: auto !important;\r\n}\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ Set a variable for our button element.\r\nconst scrollToTopButton = document.getElementById('js-top');\r\n\r\n\/\/ Let's set up a function that shows our scroll-to-top button if we scroll beyond the height of the initial window.\r\nconst scrollFunc = () => {\r\n  \/\/ Get the current scroll value\r\n  let y = window.scrollY;\r\n  \r\n  \/\/ If the scroll value is greater than the window height, let's add a class to the scroll-to-top button to show it!\r\n  if (y > 0) {\r\n    scrollToTopButton.className = \"top-link show\";\r\n  } else {\r\n    scrollToTopButton.className = \"top-link hide\";\r\n  }\r\n};\r\n\r\nwindow.addEventListener(\"scroll\", scrollFunc);\r\n\r\nconst scrollToTop = () => {\r\n  \/\/ Let's set a variable for the number of pixels we are from the top of the document.\r\n  const c = document.documentElement.scrollTop || document.body.scrollTop;\r\n  \r\n  \/\/ If that number is greater than 0, we'll scroll back to 0, or the top of the document.\r\n  \/\/ We'll also animate that scroll with requestAnimationFrame:\r\n  \/\/ https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/API\/window\/requestAnimationFrame\r\n  if (c > 0) {\r\n    window.requestAnimationFrame(scrollToTop);\r\n    \/\/ ScrollTo takes an x and a y coordinate.\r\n    \/\/ Increase the '10' value to get a smoother\/slower scroll!\r\n    window.scrollTo(0, c - c \/ 10);\r\n  }\r\n};\r\n\r\n\/\/ When the button is clicked, run our ScrolltoTop function above!\r\nscrollToTopButton.onclick = function(e) {\r\n  e.preventDefault();\r\n  scrollToTop();\r\n}\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Guia de Visita NNNNN GO #1 PT EN ES AMSTRAD CPC 464 Com mais de 2 milh\u00f5es de unidades vendidas na Europa, o Amstrad CPC 464 foi, a par do Commodore 64 e do BBC Micro, um dos principais competidores do ZX Spectrum. Criado pelo do Eng. Ivor Spital, o CPC 464 surge da vontade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"wf_page_folders":[11],"class_list":["post-2323","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/pages\/2323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/comments?post=2323"}],"version-history":[{"count":5,"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/pages\/2323\/revisions"}],"predecessor-version":[{"id":5275,"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/pages\/2323\/revisions\/5275"}],"wp:attachment":[{"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/media?parent=2323"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/loadzx.com\/loadvisitorguide\/wp-json\/wp\/v2\/wf_page_folders?post=2323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}